{"id":10404,"date":"2018-10-31T09:31:40","date_gmt":"2018-10-31T08:31:40","guid":{"rendered":"https:\/\/ptmsrl.com\/agricoltura\/"},"modified":"2019-09-02T18:32:10","modified_gmt":"2019-09-02T16:32:10","slug":"landwirtschaft","status":"publish","type":"page","link":"https:\/\/ptmsrl.com\/de\/landwirtschaft\/","title":{"rendered":"LANDWIRTSCHAFT"},"content":{"rendered":"\n  <div class=\"banner has-hover has-parallax\" id=\"banner-1372895780\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-5\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/home-ptm.jpg\" class=\"bg attachment-original size-original\" alt=\"home-ptm\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-2063010023\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h1>Landwirtschaft<\/h1>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2063010023 {\n  width: 60%;\n}\n#text-box-2063010023 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1372895780 {\n  padding-top: 500px;\n}\n#banner-1372895780 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n#banner-1372895780 .banner-bg img {\n  object-position: 5% 96%;\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"row align-bottom\"  id=\"row-1971553296\">\n\n\t<div id=\"col-766554373\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 300px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte-400x400.png\" class=\"attachment-medium size-medium\" alt=\"ptm-carrobotte\" srcset=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte-400x400.png 400w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte-280x280.png 280w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte-768x768.png 768w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte-800x800.png 800w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte-40x40.png 40w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte-60x60.png 60w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte-300x300.png 300w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte-600x600.png 600w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte-100x100.png 100w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Carrobotte.png 1024w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">G\u00fclle Tankswagen<\/h5>\t\t\t\t\t\t\n<a href=\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/guelle-tankswagen\/\" class=\"button secondary\"  style=\"border-radius:99px;\">\n\t\t<span>Erfahren Sie mehr<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1307686159\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 300px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti-400x400.png\" class=\"attachment-medium size-medium\" alt=\"ptm-pesa-a-tre-punti\" srcset=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti-400x400.png 400w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti-280x280.png 280w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti-768x768.png 768w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti-800x800.png 800w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti-40x40.png 40w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti-60x60.png 60w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti-300x300.png 300w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti-600x600.png 600w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti-100x100.png 100w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Pesa-a-tre-punti.png 1024w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Wiegedreieck<\/h5>\t\t\t\t\t\t\n<a href=\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/wiegedreieck\/\" class=\"button secondary\"  style=\"border-radius:99px;\">\n\t\t<span>Erfahren Sie mehr<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1983004663\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 300px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati-400x400.png\" class=\"attachment-medium size-medium\" alt=\"ptm-rimorchi-e-trainati\" srcset=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati-400x400.png 400w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati-280x280.png 280w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati-768x768.png 768w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati-800x800.png 800w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati-40x40.png 40w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati-60x60.png 60w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati-300x300.png 300w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati-600x600.png 600w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati-100x100.png 100w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Rimorchi-e-trainati.png 1024w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Anh\u00e4nger<\/h5>\t\t\t\t\t\t\n<a href=\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/anhaenger\/\" class=\"button secondary\"  style=\"border-radius:99px;\">\n\t\t<span>Erfahren Sie mehr<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1900027535\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1900027535 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-bottom\"  id=\"row-940193501\">\n\n\t<div id=\"col-53195008\" class=\"col medium-4 small-12 large-4\"  data-animate=\"blurIn\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 300px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1-400x400.png\" class=\"attachment-medium size-medium\" alt=\"ptm-macinazione-miscelazione-dosaggio\" srcset=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1-400x400.png 400w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1-280x280.png 280w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1-768x768.png 768w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1-800x800.png 800w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1-40x40.png 40w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1-60x60.png 60w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1-300x300.png 300w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1-600x600.png 600w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1-100x100.png 100w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Macinazione-miscelazione-dosaggio-1.png 1024w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Mahl-, Misch- und Dosiersysteme<\/h5>\t\t\t\t\t\t\n<a href=\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/mahl-misch-und-dosiersysteme\/\" class=\"button secondary\"  style=\"border-radius:99px;\">\n\t\t<span>Erfahren Sie mehr<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-585773390\" class=\"col medium-4 small-12 large-4\"  data-animate=\"blurIn\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 300px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno-400x400.png\" class=\"attachment-medium size-medium\" alt=\"ptm-analisi-carrobotte-e-balle-di-fieno\" srcset=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno-400x400.png 400w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno-280x280.png 280w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno-768x768.png 768w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno-800x800.png 800w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno-40x40.png 40w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno-60x60.png 60w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno-300x300.png 300w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno-600x600.png 600w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno-100x100.png 100w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Analisi-Carrobotte-e-balle-di-fieno.png 1024w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Analyse<\/h5>\t\t\t\t\t\t\n<a href=\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/analyse\/\" class=\"button secondary\"  style=\"border-radius:99px;\">\n\t\t<span>Erfahren Sie mehr<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-854638895\" class=\"col medium-4 small-12 large-4\"  data-animate=\"blurIn\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 300px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1-400x400.png\" class=\"attachment-medium size-medium\" alt=\"ptm-impianti-biogas\" srcset=\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1-400x400.png 400w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1-280x280.png 280w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1-768x768.png 768w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1-800x800.png 800w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1-40x40.png 40w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1-60x60.png 60w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1-300x300.png 300w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1-600x600.png 600w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1-100x100.png 100w, https:\/\/ptmsrl.com\/wp-content\/uploads\/2019\/02\/PTM-Impianti-Biogas-1.png 1024w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Biogasanlagen<\/h5>\t\t\t\t\t\t\n<a href=\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/biogasanlagen\/\" class=\"button secondary\"  style=\"border-radius:99px;\">\n\t\t<span>Erfahren Sie mehr<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-408736568\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-408736568 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-10404","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PTM Srl | LANDWIRTSCHAFT: Prodotti e Software del Settore<\/title>\n<meta name=\"description\" content=\"PTM srl progetta e sviluppa Tecnologie e Software applicati all&#039;Agricoltura per l&#039;analisi e la gestione degli impianti Agricoli.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PTM Srl | LANDWIRTSCHAFT: Prodotti e Software del Settore\" \/>\n<meta property=\"og:description\" content=\"PTM srl progetta e sviluppa Tecnologie e Software applicati all&#039;Agricoltura per l&#039;analisi e la gestione degli impianti Agricoli.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"PTM Srl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/believingintechnology\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-02T16:32:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ptm\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/\",\"url\":\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/\",\"name\":\"PTM Srl | LANDWIRTSCHAFT: Prodotti e Software del Settore\",\"isPartOf\":{\"@id\":\"https:\/\/ptmsrl.com\/#website\"},\"datePublished\":\"2018-10-31T08:31:40+00:00\",\"dateModified\":\"2019-09-02T16:32:10+00:00\",\"description\":\"PTM srl progetta e sviluppa Tecnologie e Software applicati all'Agricoltura per l'analisi e la gestione degli impianti Agricoli.\",\"breadcrumb\":{\"@id\":\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ptmsrl.com\/de\/landwirtschaft\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ptmsrl.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LANDWIRTSCHAFT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ptmsrl.com\/#website\",\"url\":\"https:\/\/ptmsrl.com\/\",\"name\":\"PTM Srl\",\"description\":\"\u041c\u042b \u041f\u0420\u041e\u0418\u0417\u0412\u041e\u0414\u0418\u041c \u041a\u0410\u0427\u0415\u0421\u0422\u0412\u041e, \u041a\u041e\u0422\u041e\u0420\u041e\u0415 \u0418\u041c\u0415\u0415\u0422 \u041e\u0421\u041e\u0411\u042b\u0419 \u0412\u0415\u0421\",\"publisher\":{\"@id\":\"https:\/\/ptmsrl.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ptmsrl.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ptmsrl.com\/#organization\",\"name\":\"PTM srl\",\"url\":\"https:\/\/ptmsrl.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/ptmsrl.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2018\/10\/LOGO-PTM.png\",\"contentUrl\":\"https:\/\/ptmsrl.com\/wp-content\/uploads\/2018\/10\/LOGO-PTM.png\",\"width\":1000,\"height\":500,\"caption\":\"PTM srl\"},\"image\":{\"@id\":\"https:\/\/ptmsrl.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/believingintechnology\/\",\"https:\/\/x.com\/ptm\",\"https:\/\/www.linkedin.com\/company\/ptm-s-r-l\/\",\"https:\/\/www.youtube.com\/channel\/UCPSOS0MaR-4jDkAD3HkAC7A\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PTM Srl | LANDWIRTSCHAFT: Prodotti e Software del Settore","description":"PTM srl progetta e sviluppa Tecnologie e Software applicati all'Agricoltura per l'analisi e la gestione degli impianti Agricoli.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ptmsrl.com\/de\/landwirtschaft\/","og_locale":"de_DE","og_type":"article","og_title":"PTM Srl | LANDWIRTSCHAFT: Prodotti e Software del Settore","og_description":"PTM srl progetta e sviluppa Tecnologie e Software applicati all'Agricoltura per l'analisi e la gestione degli impianti Agricoli.","og_url":"https:\/\/ptmsrl.com\/de\/landwirtschaft\/","og_site_name":"PTM Srl","article_publisher":"https:\/\/www.facebook.com\/believingintechnology\/","article_modified_time":"2019-09-02T16:32:10+00:00","twitter_card":"summary_large_image","twitter_site":"@ptm","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ptmsrl.com\/de\/landwirtschaft\/","url":"https:\/\/ptmsrl.com\/de\/landwirtschaft\/","name":"PTM Srl | LANDWIRTSCHAFT: Prodotti e Software del Settore","isPartOf":{"@id":"https:\/\/ptmsrl.com\/#website"},"datePublished":"2018-10-31T08:31:40+00:00","dateModified":"2019-09-02T16:32:10+00:00","description":"PTM srl progetta e sviluppa Tecnologie e Software applicati all'Agricoltura per l'analisi e la gestione degli impianti Agricoli.","breadcrumb":{"@id":"https:\/\/ptmsrl.com\/de\/landwirtschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ptmsrl.com\/de\/landwirtschaft\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ptmsrl.com\/de\/landwirtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ptmsrl.com\/de\/"},{"@type":"ListItem","position":2,"name":"LANDWIRTSCHAFT"}]},{"@type":"WebSite","@id":"https:\/\/ptmsrl.com\/#website","url":"https:\/\/ptmsrl.com\/","name":"PTM Srl","description":"\u041c\u042b \u041f\u0420\u041e\u0418\u0417\u0412\u041e\u0414\u0418\u041c \u041a\u0410\u0427\u0415\u0421\u0422\u0412\u041e, \u041a\u041e\u0422\u041e\u0420\u041e\u0415 \u0418\u041c\u0415\u0415\u0422 \u041e\u0421\u041e\u0411\u042b\u0419 \u0412\u0415\u0421","publisher":{"@id":"https:\/\/ptmsrl.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ptmsrl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ptmsrl.com\/#organization","name":"PTM srl","url":"https:\/\/ptmsrl.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ptmsrl.com\/#\/schema\/logo\/image\/","url":"https:\/\/ptmsrl.com\/wp-content\/uploads\/2018\/10\/LOGO-PTM.png","contentUrl":"https:\/\/ptmsrl.com\/wp-content\/uploads\/2018\/10\/LOGO-PTM.png","width":1000,"height":500,"caption":"PTM srl"},"image":{"@id":"https:\/\/ptmsrl.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/believingintechnology\/","https:\/\/x.com\/ptm","https:\/\/www.linkedin.com\/company\/ptm-s-r-l\/","https:\/\/www.youtube.com\/channel\/UCPSOS0MaR-4jDkAD3HkAC7A"]}]}},"_links":{"self":[{"href":"https:\/\/ptmsrl.com\/de\/wp-json\/wp\/v2\/pages\/10404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptmsrl.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ptmsrl.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ptmsrl.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ptmsrl.com\/de\/wp-json\/wp\/v2\/comments?post=10404"}],"version-history":[{"count":0,"href":"https:\/\/ptmsrl.com\/de\/wp-json\/wp\/v2\/pages\/10404\/revisions"}],"wp:attachment":[{"href":"https:\/\/ptmsrl.com\/de\/wp-json\/wp\/v2\/media?parent=10404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}